{"id":2411,"date":"2014-09-01T12:50:31","date_gmt":"2014-09-01T10:50:31","guid":{"rendered":"https:\/\/www.maestrodolio.it\/?p=2411\/"},"modified":"2017-05-23T15:02:55","modified_gmt":"2017-05-23T13:02:55","slug":"un-extra-vergine-capace-raccogliere-tutti-profumi-sicilia-teatro-naturale","status":"publish","type":"post","link":"https:\/\/www.maestrodolio.it\/it\/un-extra-vergine-capace-raccogliere-tutti-profumi-sicilia-teatro-naturale\/","title":{"rendered":"Quando un extra vergine \u00e8 capace di raccogliere tutti i profumi di Sicilia &#8211; da Teatro Naturale"},"content":{"rendered":"<p><em>&#8220;[&#8230;] nel fulmine di luce ancora giaccio<\/em><br \/>\n<em>infante a mani aperte,<\/em><br \/>\n<em>a rive d&#8217;alberi e fiumi:<\/em><br \/>\n<em>ivi la latomia d&#8217;arancio greco<\/em><br \/>\n<em>feconda per gli imenei dei numi.&#8221;<\/em><\/p>\n<p>Cavalli di luna e di vulcani<\/p>\n<p>Salvatore Quasimodo evoca la sua terra natia, la Sicilia mitologica legata alla sua infanzia. Cita le latomie &#8211; antiche cave greco-romane\u00a0da cui venivano prelevati grandi blocchi di tufo calcareo per la costruzione delle citt\u00e0 &#8211; oggi parte integrante del paesaggio siciliano.<\/p>\n<p>Ho avuto la fortuna di poter ammirare da vicino questo patrimonio artistico &#8211; culturale, durante uno dei viaggi dell&#8217;olio, quando sai bene che, inevitabilmente, ti imbatterai nelle meraviglie naturali della nostra terra.<\/p>\n<p>Nino Centonze mi ha dato la possibilit\u00e0 di addentrarmi in queste rientranze di storia, grazie alla meravigliosa posizione in cui si trova la sua azienda, &#8220;Case di Latomie&#8221;.<br \/>\nL&#8217;azienda agricola biologica \u00e8 di propriet\u00e0 della famiglia Centonze dal 1953 e si estende su una superficie di oltre trenta ettari, interamente coltivata a uliveti e agrumeti.<\/p>\n<p>Il vulcanico Nino \u00e8 attento a tutto, al bench\u00e9 minimo dettaglio: dal packaging del suo olio &#8211; ci si potrebbe confondere con una preziosa bottiglia di profumo francese &#8211; alla calda ospitalit\u00e0 del suo agriturismo, struttura incredibilmente posizionata dagli dei di Quasimodo in un luogo ideale per sentire il sole della Sicilia, passeggiando tra i sentieri segnati dalle conigliere, antichi muri di recinzione a pietra a secco.<\/p>\n<p>L&#8217;olio biologico &#8220;Centonze&#8221; sprigiona profumi di Sicilia, dal picciolo di pomodoro, alla foglia di cardo, con un sentore agrumato di fiore di zagara. In bocca la melanzana va a braccetto con la piccantezza del peperoncino in piacevole armonia.<\/p>\n<p>In attesa di un viaggio in Sicilia, perch\u00e9 non sentirne i sapori su un piatto di insalata con arance e olive nere? Condita con l&#8217;olio di Nino, ovviamente.<\/p>\n<p>&nbsp;<\/p>\n<p>Azienda Agricola Antonino Centonze<br \/>\nCastelvetrano (TP)<br \/>\noliocentonze.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;[&#8230;] nel fulmine di luce ancora giaccio infante a mani aperte, a rive d&#8217;alberi e fiumi: ivi la latomia d&#8217;arancio greco feconda per gli imenei dei numi.&#8221; Cavalli di luna&hellip;<\/p>\n<p><a href=\"https:\/\/www.maestrodolio.it\/it\/un-extra-vergine-capace-raccogliere-tutti-profumi-sicilia-teatro-naturale\/\" class=\"btn btn-olive\">Leggi tutto <i class=\"glyphicon glyphicon-chevron-right\"><\/i><\/a><\/p>\n","protected":false},"author":3,"featured_media":2412,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-2411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.maestrodolio.it\/wp-content\/uploads\/2017\/05\/IMG_6074.jpg?fit=370%2C300&ssl=1","_links":{"self":[{"href":"https:\/\/www.maestrodolio.it\/it\/wp-json\/wp\/v2\/posts\/2411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maestrodolio.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.maestrodolio.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.maestrodolio.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maestrodolio.it\/it\/wp-json\/wp\/v2\/comments?post=2411"}],"version-history":[{"count":1,"href":"https:\/\/www.maestrodolio.it\/it\/wp-json\/wp\/v2\/posts\/2411\/revisions"}],"predecessor-version":[{"id":2414,"href":"https:\/\/www.maestrodolio.it\/it\/wp-json\/wp\/v2\/posts\/2411\/revisions\/2414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maestrodolio.it\/it\/wp-json\/wp\/v2\/media\/2412"}],"wp:attachment":[{"href":"https:\/\/www.maestrodolio.it\/it\/wp-json\/wp\/v2\/media?parent=2411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.maestrodolio.it\/it\/wp-json\/wp\/v2\/categories?post=2411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.maestrodolio.it\/it\/wp-json\/wp\/v2\/tags?post=2411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}